{"id":205,"count":3,"description":"","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/barrio\/francisco-antonio-zea\/","name":"Francisco Antonio Zea","slug":"francisco-antonio-zea","taxonomy":"barrio","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/barrio\/205"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/barrio"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/taxonomies\/barrio"}],"wp:post_type":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/sedes_alcaldia?barrio=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}