{"id":273449,"date":"2023-10-30T12:04:03","date_gmt":"2023-10-30T17:04:03","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/?post_type=normativa-fao&#038;p=273449"},"modified":"2023-10-30T12:04:03","modified_gmt":"2023-10-30T17:04:03","slug":"concepto-mercados-campesinos_0000011_2019","status":"publish","type":"normativa-fao","link":"https:\/\/www.medellin.gov.co\/es\/normativa-fao\/concepto-mercados-campesinos_0000011_2019\/","title":{"rendered":"Concepto mercados campesinos_0000011_2019"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Concepto jur\u00eddico favorable sobre el proyecto de Acuerdo \u201cpor medio del cual se reestructura el programa Mercados Campesinos\u201d<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concepto jur\u00eddico favorable sobre el proyecto de Acuerdo \u201cpor medio del cual se reestructura el programa Mercados Campesinos\u201d<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"categories":[24],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/normativa-fao\/273449"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/normativa-fao"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/normativa-fao"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=273449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=273449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=273449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}