{"id":124759,"date":"2022-10-28T18:23:03","date_gmt":"2022-10-28T23:23:03","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/?p=124759"},"modified":"2022-10-28T18:23:03","modified_gmt":"2022-10-28T23:23:03","slug":"con-diez-mesas-de-trabajo-medellin-avanza-en-su-transformacion-como-distrito-especial-de-ciencia-tecnologia-e-innovacion","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/con-diez-mesas-de-trabajo-medellin-avanza-en-su-transformacion-como-distrito-especial-de-ciencia-tecnologia-e-innovacion\/","title":{"rendered":"Con diez mesas de trabajo, Medell\u00edn avanza en su transformaci\u00f3n como Distrito Especial de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n"},"content":{"rendered":"<ul>\n<li>Funciones de salud, cultura y turismo, que antes estaban en manos de la Gobernaci\u00f3n de Antioquia, pasan a ser del Distrito de Medell\u00edn.<\/li>\n<li>En un evento de Gerencia Jur\u00eddica P\u00fablica, se socializaron las acciones internas de transici\u00f3n de Municipio a Distrito.<\/li>\n<\/ul>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n\t<div class=\"wp-playlist wp-audio-playlist wp-playlist-light\">\n\t\t\t<div class=\"wp-playlist-current-item\"><\/div>\n\t\t<audio controls=\"controls\" preload=\"none\" width=\"640\"\n\t\t\t><\/audio>\n\t<div class=\"wp-playlist-next\"><\/div>\n\t<div class=\"wp-playlist-prev\"><\/div>\n\t<noscript>\n\t<ol>\n\t\t<li><a href='https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2022\/10\/mesas-de-trabajo.mp3'>Palabras de Natalia Andrea Jim\u00e9nez P\u00e9rez, secretaria general.<\/a><\/li>\t<\/ol>\n\t<\/noscript>\n\t<script type=\"application\/json\" class=\"wp-playlist-script\">{\"type\":\"audio\",\"tracklist\":true,\"tracknumbers\":true,\"images\":true,\"artists\":true,\"tracks\":[{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mesas-de-trabajo.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"Palabras de Natalia Andrea Jim\\u00e9nez P\\u00e9rez, secretaria general.\",\"caption\":\"\",\"description\":\"\\u00abmesas-de-trabajo\\u00bb. Lanzamiento: 2022.\",\"meta\":{\"year\":\"2022\",\"length_formatted\":\"1:12\"},\"image\":{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-includes\\\/images\\\/media\\\/audio.png\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-includes\\\/images\\\/media\\\/audio.png\",\"width\":48,\"height\":64}}]}<\/script>\n<\/div>\n\t\n<p>Para la transici\u00f3n de Municipio a Distrito, la Alcald\u00eda de Medell\u00edn cre\u00f3 diez mesas de trabajo: siete sectoriales, encargadas de los temas relacionados con la comunidad, y tres transversales, que apoyan la gesti\u00f3n del Conglomerado P\u00fablico, y en las que han participado, activamente, las 24 secretar\u00edas y los 37 entes descentralizados. En este sentido, internamente se vela por el cumplimiento del Acto Legislativo 01 de 2021 el cual eleva la categor\u00eda de Municipio a Distrito, en una primera etapa, y su posterior aplicaci\u00f3n.<\/p>\n<p><em>\u201cHoy, nuestro tema principal es la transformaci\u00f3n de Municipio a Distrito, proceso en el cual llevamos trabajando un a\u00f1o de manera articulada en nuestra alcald\u00eda y en el cual se han creado tres mesas principales: la jur\u00eddica, coordinada por la Secretar\u00eda General; la financiera y fiscal, por la Secretar\u00eda de Hacienda; y la de ciencia, tecnolog\u00eda e innovaci\u00f3n, por la Secretar\u00eda de Desarrollo Econ\u00f3mico. En este ejercicio han participado todas las dependencias del Conglomerado P\u00fablico. En los siguientes cinco a\u00f1os esperamos terminar de consolidar este proceso de transformaci\u00f3n de Municipio a Distrito, de acuerdo con la ley org\u00e1nica que est\u00e1 aprobada por el Congreso de la Rep\u00fablica\u201d<\/em>, manifest\u00f3 la secretaria general, Natalia Andrea Jim\u00e9nez P\u00e9rez.<\/p>\n<p>Elevar la categor\u00eda de Municipio a Distrito le da mayor autonom\u00eda a Medell\u00edn para el manejo de la gesti\u00f3n en temas relacionados con cultura, salud, turismo, ciencia, tecnolog\u00eda e innovaci\u00f3n, funciones que anteriormente estaban en manos de la Gobernaci\u00f3n de Antioquia.<\/p>\n<p>El beneficio para los ciudadanos consiste en la vocaci\u00f3n que ahora tiene Medell\u00edn en relaci\u00f3n con la creaci\u00f3n de empresas para estos sectores, con incentivos que permitan su desarrollo y que se contemplan en la ley org\u00e1nica que est\u00e1 para sanci\u00f3n; y en otro aspecto, en la educaci\u00f3n b\u00e1sica, media y profesional, que estar\u00e1n orientadas a potencializar los contenidos de ciencia, tecnolog\u00eda e innovaci\u00f3n.<\/p>\n<p>Actualmente, la ruta de transformaci\u00f3n se encuentra en la segunda etapa, que contempla tres fases: la aplicaci\u00f3n del Acto Legislativo 01, el dise\u00f1o del plan de transici\u00f3n y la ejecuci\u00f3n del mismo, que tiene un plazo de hasta cinco a\u00f1os para ponerse en pr\u00e1ctica, a partir de la sanci\u00f3n del presidente de la Rep\u00fablica; trabajo que es acompa\u00f1ado por la Secretar\u00eda General.<\/p>\n<p>Por lo anterior y para\u00a0 poner en com\u00fan lo que ha representado el cambio interno de Distrito a Municipio, la Alcald\u00eda de Medell\u00edn realiz\u00f3 la s\u00e9ptima edici\u00f3n del evento Gerencia Jur\u00eddica P\u00fablica, este a\u00f1o enfocado en el tema \u201cMedell\u00edn Distrito Especial de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n\u201d, en Plaza Mayor, al cual asistieron cerca de 150 abogados con el\u00a0 prop\u00f3sito de socializar el ejercicio interno que se ha desarrollado en lo administrativo y jur\u00eddico para la entidad, desde el a\u00f1o 2021, en un formato de capacitaci\u00f3n para los servidores que participan en el proceso de gesti\u00f3n jur\u00eddica.<\/p>\n<p><em>\u201cEs importante que resaltemos por qu\u00e9 somos Distrito, por qu\u00e9 se dio esta reforma constitucional y por qu\u00e9 estamos avanzando en un proyecto de ley para tener esas herramientas, instrumentos y mecanismos que nos permitan asumir competencias como entidad territorial distrital, y es nuestra vocaci\u00f3n. Medell\u00edn viene en un proceso de transformaci\u00f3n de ser una ciudad industrial a ser una ciudad de servicios en la que la ciencia, la tecnolog\u00eda y la innovaci\u00f3n han sido pilares fundamentales para lograr la transformaci\u00f3n, no solo econ\u00f3mica y territorial, sino social\u201d,<\/em> explic\u00f3 la l\u00edder de la Unidad de Articulaci\u00f3n Regional del Departamento Administrativo de Planeaci\u00f3n, Adriana Patricia Grisales.<\/p>\n<p>En el evento, se destacaron las experiencias exitosas narradas por ponentes nacionales e internacionales de Panam\u00e1, Brasil y Espa\u00f1a, en torno a la ciencia, la tecnolog\u00eda y la innovaci\u00f3n.<\/p>\n<p>El abogado Jos\u00e9 Francisco Vega Gallardo, de Panam\u00e1, quien ha sido miembro del Comit\u00e9 Ejecutivo del Instituto de Gobierno Corporativo de Panam\u00e1, habl\u00f3 sobre las cinco claves jur\u00eddicas para pensar las Smart Cities.<\/p>\n<p>Anna Luisa Walter, de Santana, Brasil, reconocida por ser parte del Consejo Ejecutivo de la Academia Latinoamericana de Derechos Humanos y Empresas, y directora de Formaci\u00f3n en Tirant lo Blanch para Brasil y Colombia, expuso sobre \u201cTecnolog\u00eda, Innovaci\u00f3n Jur\u00eddica y Objetivos de Desarrollo Sostenible: desaf\u00edos y oportunidades\u201d.<\/p>\n<p>Isabel Barrios Gonz\u00e1lez, de Espa\u00f1a, quien hace parte del Departamento de Formaci\u00f3n de la Editorial Tirant lo Blanch, en donde se ha desempe\u00f1ado como gestora de proyectos y, actualmente, dirige el departamento completo de Formaci\u00f3n Espa\u00f1a y Latinoam\u00e9rica, comparti\u00f3 sobre \u201cInnovaci\u00f3n jur\u00eddica: alcance y experiencias\u201d.<\/p>\n<p>Con el desarrollo de este tipo de acciones, la Alcald\u00eda de Medell\u00edn materializa la transformaci\u00f3n de Municipio a Distrito Especial de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n, y lidera su aplicaci\u00f3n en el Derecho, as\u00ed como el correcto funcionamiento al aplicar las nuevas normativas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Funciones de salud, cultura y turismo, que antes estaban en manos de la Gobernaci\u00f3n de Antioquia, pasan a ser del Distrito de Medell\u00edn. En un evento de Gerencia Jur\u00eddica P\u00fablica, se socializaron las acciones internas &#8230;<\/p>\n","protected":false},"author":4,"featured_media":124762,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[428,455],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/124759"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=124759"}],"version-history":[{"count":1,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/124759\/revisions"}],"predecessor-version":[{"id":124771,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/124759\/revisions\/124771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/124762"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=124759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=124759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=124759"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=124759"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=124759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}