{"id":139759,"date":"2022-12-09T18:32:46","date_gmt":"2022-12-09T23:32:46","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/?p=139759"},"modified":"2022-12-09T18:32:46","modified_gmt":"2022-12-09T23:32:46","slug":"11-220-estudiantes-de-medellin-obtuvieron-doble-titulacion-gracias-a-los-programas-de-media-tecnica","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/11-220-estudiantes-de-medellin-obtuvieron-doble-titulacion-gracias-a-los-programas-de-media-tecnica\/","title":{"rendered":"11.220 estudiantes de Medell\u00edn obtuvieron doble titulaci\u00f3n gracias a los programas de Media T\u00e9cnica"},"content":{"rendered":"<ul>\n<li>Las comunas con m\u00e1s bachilleres t\u00e9cnicos graduados son Robledo, Doce de Octubre, Manrique, Buenos Aires y Castilla.<\/li>\n<li>En Medell\u00edn, el 90 % de las instituciones educativas oficiales tienen Media T\u00e9cnica.<\/li>\n<li>23.455 j\u00f3venes de los establecimientos educativos del Distrito llegaron a und\u00e9cimo grado.<\/li>\n<\/ul>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n\t<div class=\"wp-playlist wp-audio-playlist wp-playlist-light\">\n\t\t\t<div class=\"wp-playlist-current-item\"><\/div>\n\t\t<audio controls=\"controls\" preload=\"none\" width=\"640\"\n\t\t\t><\/audio>\n\t<div class=\"wp-playlist-next\"><\/div>\n\t<div class=\"wp-playlist-prev\"><\/div>\n\t<noscript>\n\t<ol>\n\t\t<li><a href='https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2022\/12\/doble-titulacion.mp3'>Palabras de Alexandra Agudelo Ruiz, secretaria de Educaci\u00f3n.<\/a><\/li>\t<\/ol>\n\t<\/noscript>\n\t<script type=\"application\/json\" class=\"wp-playlist-script\">{\"type\":\"audio\",\"tracklist\":true,\"tracknumbers\":true,\"images\":true,\"artists\":true,\"tracks\":[{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/doble-titulacion.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"Palabras de Alexandra Agudelo Ruiz, secretaria de Educaci\\u00f3n.\",\"caption\":\"\",\"description\":\"Palabras de Alexandra Agudelo Ruiz, secretaria de Educaci\\u00f3n.\",\"meta\":{\"length_formatted\":\"0:52\"},\"image\":{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-includes\\\/images\\\/media\\\/audio.png\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-includes\\\/images\\\/media\\\/audio.png\",\"width\":48,\"height\":64}}]}<\/script>\n<\/div>\n\t\n<p>En Medell\u00edn, 11.220 estudiantes obtuvieron doble titulaci\u00f3n gracias a los programas de Media T\u00e9cnica que implementa la Administraci\u00f3n Distrital en los establecimientos educativos de sus 16 comunas y cinco corregimientos.<\/p>\n<p>En total, en el Distrito de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n superaron el und\u00e9cimo grado 23.445 j\u00f3venes, de los cuales 18.406 fueron de instituciones educativas oficiales, 3.913 de colegios privados y 1.136 de establecimientos de cobertura. La comuna con m\u00e1s graduados es Robledo con 2.429 estudiantes quienes obtuvieron el t\u00edtulo de bachilleres.<\/p>\n<p><em>\u201cEste a\u00f1o fueron m\u00e1s de 23.000 graduados que entreg\u00f3 el Distrito de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n. La mitad de ellos fueron estudiantes de Media T\u00e9cnica, de los cuales el 50 % en habilidades TIC para la Cuarta Revoluci\u00f3n Industrial. La universalizaci\u00f3n de la Media T\u00e9cnica se est\u00e1 logrando. Ya m\u00e1s de 200 instituciones educativas tienen y esperamos llegar al logro final el pr\u00f3ximo a\u00f1o. Tambi\u00e9n, que los estudiantes contin\u00faen con su Computador Futuro y puedan seguir estudiando en la educaci\u00f3n postsecundaria\u201d,<\/em> afirm\u00f3 la secretaria de Educaci\u00f3n, Alexandra Agudelo Ruiz.<\/p>\n<p>En 2020, se graduaron de Media T\u00e9cnica 10.076 estudiantes y en 2021 fueron 10.429, quienes obtuvieron la doble titulaci\u00f3n. En Medell\u00edn, los programas t\u00e9cnicos son en \u00e1reas de inform\u00e1tica, energ\u00eda el\u00e9ctrica, administraci\u00f3n, artes, comercio, construcci\u00f3n, deportes, industrial, medio ambiente, salud, servicios, textil, confecci\u00f3n y moda, y turismo; con los cuales los j\u00f3venes de los grados d\u00e9cimo y und\u00e9cimo mejoran sus conocimientos y se preparan para salir al mercado laboral y aportar al sector productivo.<\/p>\n<div id=\"attachment_139765\" style=\"width: 1210px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2022\/12\/doble-titulacion-2.jpg\" target=\"_blank\" rel=\"noopener\"><img aria-describedby=\"caption-attachment-139765\" loading=\"lazy\" class=\"wp-image-139765 size-full\" title=\"Doble titulaci\u00f3n - Media T\u00e9cnica\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2022\/12\/doble-titulacion-2.jpg\" alt=\"Doble titulaci\u00f3n - Media T\u00e9cnica\" width=\"1200\" height=\"900\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2022\/12\/doble-titulacion-2.jpg 1200w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2022\/12\/doble-titulacion-2-300x225.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2022\/12\/doble-titulacion-2-1024x768.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2022\/12\/doble-titulacion-2-150x113.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2022\/12\/doble-titulacion-2-768x576.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><p id=\"caption-attachment-139765\" class=\"wp-caption-text\">Doble titulaci\u00f3n &#8211; Media T\u00e9cnica. Foto: Alcald\u00eda de Medell\u00edn<\/p><\/div>\n<p><em>\u201cLa verdad, fue bastante agradable. Estoy aqu\u00ed desde s\u00e9ptimo grado. Los profesores siempre han sido bastante comprensivos conmigo e intentan apoyar mucho a los estudiantes, as\u00ed sea que vayan mal; los motivan para que puedan ganar los a\u00f1os y mejoren. Lo que m\u00e1s me llevo es el cari\u00f1o que tienen los profesores hacia a sus estudiantes, por el aprendizaje, por ense\u00f1arles, por la motivaci\u00f3n que brindan para tener un mejor futuro\u201d,<\/em> expres\u00f3 el graduado de la Instituci\u00f3n Educativa Miraflores, Jhoan Yesid Ortiz Saldarriaga.<\/p>\n<p>El n\u00famero de bachilleres t\u00e9cnicos graduados por territorio se distribuye de la siguiente manera: Popular (766), Santa Cruz (502), Manrique (989), Aranjuez (777), Castilla (781), Doce de Octubre (997), Robledo (1.132), Villa Hermosa (552), Buenos Aires (871), La Candelaria (771), Laureles\/Estadio (91), La Am\u00e9rica (395), San Javier (434), El Poblado (298), Guayabal (239), Bel\u00e9n (626), San Sebasti\u00e1n de Palmitas (40), San Crist\u00f3bal (290), Altavista (33), San Antonio de Prado (576) y Santa Elena (60).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las comunas con m\u00e1s bachilleres t\u00e9cnicos graduados son Robledo, Doce de Octubre, Manrique, Buenos Aires y Castilla. En Medell\u00edn, el 90 % de las instituciones educativas oficiales tienen Media T\u00e9cnica. 23.455 j\u00f3venes de los establecimientos &#8230;<\/p>\n","protected":false},"author":4,"featured_media":139763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[431],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/139759"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=139759"}],"version-history":[{"count":1,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/139759\/revisions"}],"predecessor-version":[{"id":139768,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/139759\/revisions\/139768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/139763"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=139759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=139759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=139759"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=139759"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=139759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}