{"id":170280,"date":"2023-03-21T12:04:43","date_gmt":"2023-03-21T17:04:43","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/?p=170280"},"modified":"2023-03-21T15:48:13","modified_gmt":"2023-03-21T20:48:13","slug":"despues-de-12-anos-de-espera-lennon-al-fin-encontro-un-hogar","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/despues-de-12-anos-de-espera-lennon-al-fin-encontro-un-hogar\/","title":{"rendered":"Despu\u00e9s de 12 a\u00f1os de espera, Lennon al fin encontr\u00f3 un hogar"},"content":{"rendered":"<blockquote><p><em>El perro con m\u00e1s tiempo de permanencia en el <a href=\"https:\/\/www.medellin.gov.co\/laperla\">Centro de Bienestar Animal La Perla<\/a> -Lennon- luego de 12 a\u00f1os de estar all\u00ed a la espera de un hogar, encontr\u00f3 en los brazos y en el amor de una familia, el que ser\u00e1 ser\u00e1 su refugio sagrado por el resto de su vida.<\/em><\/p><\/blockquote>\n<p><div class=\"iframe-container\"><iframe width=\"100%\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/lI0f9Ga1JiI\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div><\/p>\n<p>Con tan solo 25 d\u00edas de nacido, Lennon fue abandonado a su suerte el 21 de octubre de 2011 en una calle del sector del <a href=\"https:\/\/www.medellin.gov.co\/es\/corregimientos\/gerencia\/altavista\/\">corregimiento Altavista<\/a>, al occidente de la ciudad. Este cachorro criollo no entend\u00eda por qu\u00e9 de un momento a otro se encontraba en un lugar que no conoc\u00eda, en medio del fr\u00edo y bajo la mirada de algunas personas que nunca hab\u00eda visto y que trataban de ayudarlo y brindarle mejores condiciones en ese momento de angustia y temor.<\/p>\n<p>Las personas del sector alertaron a las autoridades sobre este caso de maltrato y abandono y el equipo de profesionales del <a href=\"https:\/\/www.medellin.gov.co\/laperla\">Centro de Bienestar Animal La Perla<\/a> hizo efectivo el rescate de Lennon, quien fue valorado y entr\u00f3 en proceso de recuperaci\u00f3n.<\/p>\n<div id=\"attachment_170293\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_1.jpg\" target=\"_blank\" rel=\"noopener\"><img aria-describedby=\"caption-attachment-170293\" loading=\"lazy\" class=\"wp-image-170293 size-large\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_1-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_1-1024x683.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_1-300x200.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_1-150x100.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_1-768x512.jpg 768w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_1.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-170293\" class=\"wp-caption-text\">Juliana Hern\u00e1ndez Galeano, adoptante de Lennon<\/p><\/div>\n<p>El diagn\u00f3stico de Lennon no fue nada positivo y a sus escasos 25 d\u00edas ya mostraba las marcas del maltrato y la falta de atenci\u00f3n que hab\u00eda sufrido por parte de las personas responsables de su cuidado. Al momento de su rescate presentaba baja condici\u00f3n corporal, desnutrici\u00f3n, deshidrataci\u00f3n y alteraciones en la piel por presencia de par\u00e1sitos externos, pulgas y garrapatas.<\/p>\n<p>Lennon hace parte de las fr\u00edas estad\u00edsticas que cada a\u00f1o ponen en alerta, que en varios sectores de la ciudad, algunas personas no asumen un cuidado responsable de los animales de compa\u00f1\u00eda. Esta situaci\u00f3n se repite con frecuencia en barrios y comunas de la capital antioque\u00f1a. Una clara muestra de esta situaci\u00f3n, son las cifras del \u00faltimo a\u00f1o, cuando el equipo de profesionales del <a href=\"https:\/\/www.medellin.gov.co\/laperla\">Centro de Bienestar Animal La Perla<\/a> rescat\u00f3 por maltrato o abandono a 2.749 perros y gatos, que cuando \u00a0ingresan al Centro de Bienestar Animal reciben las atenciones necesarias para su recuperaci\u00f3n y quedan disponibles para los procesos de adopci\u00f3n.<\/p>\n<div id=\"attachment_170288\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_5.jpg\" target=\"_blank\" rel=\"noopener\"><img aria-describedby=\"caption-attachment-170288\" loading=\"lazy\" class=\"wp-image-170288 size-large\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_5-1024x682.jpg\" alt=\"Lennon\" width=\"1024\" height=\"682\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_5-1024x682.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_5-300x200.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_5-150x100.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_5-768x512.jpg 768w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_5.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-170288\" class=\"wp-caption-text\">Juliana Hern\u00e1ndez Galeano, adoptante de Lennon<\/p><\/div>\n<blockquote><p><strong>Te puede interesar:\u00a0<\/strong><a href=\"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/quieres-adoptar-a-majin-buu-un-sobreviviente-que-solo-busca-amor-y-compania\/\"><em>\u00bfQuieres adoptar a Majin Buu, un sobreviviente que solo busca amor y compa\u00f1\u00eda?<\/em><\/a><\/p><\/blockquote>\n<p><strong>Los cuidados de Lennon<\/strong><\/p>\n<p>Lennon recibi\u00f3 atenciones especiales durante algunas semanas para recuperar su estado de salud, lograr un peso adecuado, adem\u00e1s de la desparasitaci\u00f3n, vacunaci\u00f3n, implantaci\u00f3n de microchip; qued\u00f3 disponible para los procesos de adopci\u00f3n, incluso en algunas jornadas especiales, hizo parte de los caninos que estaban listos para recibir la oportunidad de un nuevo hogar, pero no tuvo la suerte o la familia que quisiera acogerlo y nuevamente regres\u00f3 a <a href=\"https:\/\/www.medellin.gov.co\/laperla\">La Perla<\/a>.<\/p>\n<p>All\u00ed estuvo durante 12 a\u00f1os recibiendo todas las atenciones y el amor que los profesionales y funcionarios del <a href=\"https:\/\/www.medellin.gov.co\/laperla\">Centro de Bienestar Animal<\/a>\u00a0le brindan a los cerca de 2.000 caninos y felinos que se encuentran albergados en ese lugar; pero estos animales de compa\u00f1\u00eda tambi\u00e9n necesitan una familia que les brinde en todo momento ese cari\u00f1o y el cuidado que requieren.<\/p>\n<div id=\"attachment_170282\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_8.jpg\" target=\"_blank\" rel=\"noopener\"><img aria-describedby=\"caption-attachment-170282\" loading=\"lazy\" class=\"wp-image-170282 size-large\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_8-1024x682.jpg\" alt=\"Lennon\" width=\"1024\" height=\"682\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_8-1024x682.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_8-300x200.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_8-150x100.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_8-768x512.jpg 768w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_8.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-170282\" class=\"wp-caption-text\">Lennon.<\/p><\/div>\n<p>Con 12 a\u00f1os en el Centro de Bienestar Animal, Lennon tiene la triste caracter\u00edstica de ser el perro que ha estado m\u00e1s tiempo en <a href=\"https:\/\/www.medellin.gov.co\/laperla\">La Perla<\/a>. Toda su vida transcurri\u00f3 en el albergue al que ingres\u00f3 con menos de un mes de edad y despu\u00e9s de muchas ocasiones en la que estaba listo para recibir la oportunidad de una familia sin una respuesta positiva, parec\u00eda que estaba destinado a continuar all\u00ed por mucho tiempo o por el resto de su vida.<em>\u00a0<\/em><\/p>\n<p><div class=\"iframe-container\"><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/v8V-aNgRY7E\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/div><\/p>\n<p><em>\u201cLennon es un perrito de 12 a\u00f1os que fue rescatado con pocos d\u00edas de nacido, pesaba escasos 800 gramos y no estaba en las mejores condiciones. Es un perrito ya viejito, muy amoroso y en toda su vida no ha conocido un amor distinto al de los que trabajamos en <a href=\"https:\/\/www.medellin.gov.co\/laperla\">La Perla<\/a> y est\u00e1 dispuesto a dar mucho amor en un hogar donde lo quieran mucho, porque toda su vida ha esperado por un hogar cari\u00f1oso que lo adopte\u201d,<\/em> comenta Juan Esteban Herrera, m\u00e9dico veterinario de <a href=\"https:\/\/www.medellin.gov.co\/laperla\">La Perla<\/a>.<\/p>\n<div id=\"attachment_170290\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_historia_3.jpg\" target=\"_blank\" rel=\"noopener\"><img aria-describedby=\"caption-attachment-170290\" loading=\"lazy\" class=\"wp-image-170290 size-large\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_historia_3-1024x694.jpg\" alt=\"Juan Esteban Herrera, m\u00e9dico veterinario de La Perla\" width=\"1024\" height=\"694\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_historia_3-1024x694.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_historia_3-300x203.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_historia_3-150x102.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_historia_3-768x520.jpg 768w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_historia_3.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-170290\" class=\"wp-caption-text\">Juan Esteban Herrera, m\u00e9dico veterinario de La Perla<\/p><\/div>\n<blockquote><p><em><strong>Te puede interesar:<\/strong> <a href=\"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/centro-de-bienestar-la-perla\/\">Sanders, una nueva oportunidad para todos<\/a><\/em><\/p><\/blockquote>\n<p><strong>Lennon y su nueva familia<\/strong><\/p>\n<p>Lennon fue el protagonista de una de las publicaciones en las redes sociales de la Alcald\u00eda de Medell\u00edn y su historia la conocieron muchas personas, entre estas los integrantes de la familia Hern\u00e1ndez Galeano, que decidieron darle una nueva oportunidad, la misma que llevaba 12 a\u00f1os esperando y que por fin le llegaba a este canino criollo, que, como la mayor\u00eda de los perros disponibles para adoptar en el Centro de Bienestar Animal, es tranquilo, noble, obediente y cari\u00f1oso.<\/p>\n<p><div class=\"iframe-container\"><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/iXvfCdf2JmA\" width=\"100&amp;\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/div><\/p>\n<p>Los integrantes de la familia iniciaron los contactos con <a href=\"https:\/\/www.medellin.gov.co\/laperla\">La Perla<\/a> para la adopci\u00f3n de Lennon, que seg\u00fan la informaci\u00f3n recibida, ya ten\u00eda otras personas interesadas en brindarle una nueva oportunidad, raz\u00f3n por la cual agilizaron los tr\u00e1mites y recorrieron 50 kil\u00f3metros desde el sector de El Porvenir en el municipio de Rionegro, oriente antioque\u00f1o, hasta el <a href=\"https:\/\/www.medellin.gov.co\/es\/corregimientos\/gerencia\/altavista\/\">corregimiento Altavista<\/a> al occidente de Medell\u00edn, donde est\u00e1 ubicado el <a href=\"https:\/\/www.medellin.gov.co\/laperla\">Centro de Bienestar Animal<\/a>\u00a0y poder culminar ese proceso.<\/p>\n<p>La adopci\u00f3n fue el 5 de marzo y la familia recibi\u00f3 el acompa\u00f1amiento de los profesionales del <a href=\"https:\/\/www.medellin.gov.co\/laperla\">Centro de Bienestar Animal<\/a>, que entregaron la informaci\u00f3n de Lennon y conocieron el entorno de los nuevos cuidadores.<\/p>\n<div id=\"attachment_170287\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_6.jpg\" target=\"_blank\" rel=\"noopener\"><img aria-describedby=\"caption-attachment-170287\" loading=\"lazy\" class=\"wp-image-170287 size-large\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_6-1024x768.jpg\" alt=\"Lennon\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_6-1024x768.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_6-300x225.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_6-150x113.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_6-768x576.jpg 768w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Enon_historia_6.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-170287\" class=\"wp-caption-text\">Juliana Hern\u00e1ndez Galeano, adoptante de Lennon<\/p><\/div>\n<p><em>\u201cYo vi el video de Lennon y me enamor\u00e9 de \u00e9l; vi su historia en las redes; que ya llevaba 12 a\u00f1os esperando una oportunidad y, por eso, quise que el tiempo que le queda lo tuviera con una familia que le brinde mucho amor. Lennon es muy t\u00edmido, pero es demasiado amoroso; todo el tiempo quiere que lo carguen, que lo mimen; y es muy tranquilo y muy juicioso\u201d<\/em>, manifiesta Juliana Hern\u00e1ndez Galeano, adoptante de Lennon.<\/p>\n<p><span style=\"font-size: 16px;\">Lleg\u00f3 a una familia multiespecie integrada por Germ\u00e1n Hern\u00e1ndez, Paola Galeano y su hija Juliana, adem\u00e1s de los felinos: Anny, Clara, Aurora, Oslo y Par\u00eds y las caninas: Sacha y Candy, que ahora son sus compa\u00f1eras de caminatas familiares a diferentes sectores de ese municipio del oriente antioque\u00f1o, especialmente a los alrededores del R\u00edo Negro, un espacio natural a 200 metros de la vivienda de la familia que recorren por lo menos dos veces al d\u00eda.<\/span><\/p>\n<div id=\"attachment_170292\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_Historia_4.jpg\" target=\"_blank\" rel=\"noopener\"><img aria-describedby=\"caption-attachment-170292\" loading=\"lazy\" class=\"wp-image-170292 size-large\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_Historia_4-1024x683.jpg\" alt=\"Familia Hern\u00e1ndez Galeano quienes adoptaron a Lennon\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_Historia_4-1024x683.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_Historia_4-300x200.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_Historia_4-150x100.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_Historia_4-768x512.jpg 768w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2023\/03\/Lenon_Historia_4.jpg 1134w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-170292\" class=\"wp-caption-text\">Familia Hern\u00e1ndez Galeano quienes adoptaron a Lennon<\/p><\/div>\n<p><em>\u201cLennon me acompa\u00f1a a todas partes, puedo llevarlo a centros comerciales a mi trabajo, a diferentes espacios, porque es muy paciente, muy juicioso y ya no me imagino mi vida sin \u00e9l, ya me hace demasiada falta y solo hace unos d\u00edas lo adoptamos\u201d,<\/em> expresa Juliana.<\/p>\n<blockquote><p><em><strong>Te puede interesar: <\/strong><a href=\"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/como-adoptar-un-animal-de-compania-en-medellin\/\">\u00bfC\u00f3mo adoptar un animal de compa\u00f1\u00eda en Medell\u00edn?<\/a><\/em><\/p><\/blockquote>\n<p><strong>Otros como \u00e9l, esperan su oportunidad.<\/strong><\/p>\n<p>Como Lennon, otros 1.057 animales de compa\u00f1\u00eda del <a href=\"https:\/\/www.medellin.gov.co\/laperla\">Centro de Bienestar Animal La Perla<\/a> recibieron el \u00faltimo a\u00f1o una nueva oportunidad y han encontrado una nueva familia, pero todav\u00eda cerca de 1.300 perros y 25 gatos est\u00e1n disponibles para los procesos de adopci\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2021\/09\/centro-de-bienestar-animal-la-perla-aviso.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"alignnone wp-image-15545 size-large\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2021\/09\/centro-de-bienestar-animal-la-perla-aviso-1024x307.jpg\" alt=\"Centro La Perla\" width=\"1024\" height=\"307\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2021\/09\/centro-de-bienestar-animal-la-perla-aviso-1024x307.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2021\/09\/centro-de-bienestar-animal-la-perla-aviso-300x90.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2021\/09\/centro-de-bienestar-animal-la-perla-aviso-150x45.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2021\/09\/centro-de-bienestar-animal-la-perla-aviso-768x230.jpg 768w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2021\/09\/centro-de-bienestar-animal-la-perla-aviso.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Lennon recibi\u00f3 una nueva oportunidad, un nuevo hogar y una nueva familia multiespecie a la que se adapt\u00f3 f\u00e1cilmente y con la que comparte salidas, diferentes actividades.<\/p>\n<p>Una familia que tambi\u00e9n se llen\u00f3 de felicidad \u00a0con su llegada \u00a0y con poderle brindar amor y mimos a un animal de compa\u00f1\u00eda juicioso, tierno y amigable y que todos los d\u00edas con sus muestras de cari\u00f1o les confirma que la adopci\u00f3n fue la mejor opci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El perro con m\u00e1s tiempo de permanencia en el Centro de Bienestar Animal La Perla -Lennon- luego de 12 a\u00f1os de estar all\u00ed a la espera de un hogar, encontr\u00f3 en los brazos y en &#8230;<\/p>\n","protected":false},"author":17,"featured_media":170285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[446],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/170280"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=170280"}],"version-history":[{"count":10,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/170280\/revisions"}],"predecessor-version":[{"id":170565,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/170280\/revisions\/170565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/170285"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=170280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=170280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=170280"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=170280"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=170280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}