{"id":33623,"date":"2020-06-09T00:00:00","date_gmt":"2020-06-09T05:00:00","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/saladeprensa\/noticias\/cursos-pedagogicos-de-movilidad-se-reactivaran-de-manera-virtual\/"},"modified":"2022-03-27T22:13:38","modified_gmt":"2022-03-28T03:13:38","slug":"cursos-pedagogicos-de-movilidad-se-reactivaran-de-manera-virtual","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/cursos-pedagogicos-de-movilidad-se-reactivaran-de-manera-virtual\/","title":{"rendered":"Cursos pedag\u00f3gicos de Movilidad se reactivar\u00e1n de manera virtual"},"content":{"rendered":"<div class=\"wrap contenido\">\n<div class=\"noticia\">\n<div class=\"imagen\">\n<div class=\"divContImageNoticia\" style=\"background-image:url('\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer\u00eda d\u00eda a d\u00eda 2020\/500_400\/20200609_CursosMovilidad1.jpg')\" rel=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer\u00eda d\u00eda a d\u00eda 2020\/500_400\/20200609_CursosMovilidad1.jpg\"><span style=\"display:none\"\/><\/div>\n<p>Cursos pedag\u00f3gicos de Movilidad se reactivar\u00e1n de manera virtual.<\/p>\n<p>Foto Alcald\u00eda de Medell\u00edn<\/p><\/div>\n<p class=\"fecha\"><span>2020-06-09<\/span><\/p>\n<p itemprop=\"name\">Cursos pedag\u00f3gicos de Movilidad se reactivar\u00e1n de manera virtual<\/p>\n<p>Por Prensa Alcald\u00eda de Medell\u00edn<\/p>\n<div class=\"cuerpo\">\n<p><p>.: Las personas podr&aacute;n ingresar a <a href=\"http:\/\/www.medellin.gov.co\/movilidad\"><strong><span style=\"color: #3366ff;\">w<\/span><span style=\"color: #3366ff;\">ww.medellin.gov.co\/movilidad<\/span><\/strong><\/a> para realizar el cuestionario en l&iacute;nea.<br \/>.: Tambi&eacute;n se reanudar&aacute;n las audiencias de tr&aacute;nsito, la notificaci&oacute;n de comparendos y los tr&aacute;mites relacionados con el Registro Municipal.&nbsp;<\/p>\n<p>Este mi&eacute;rcoles 10 de junio se reactivar&aacute;n los cursos pedag&oacute;gicos para infractores, los cuales estaban suspendidos desde el 17 de marzo debido a la emergencia por el coronavirus, seg&uacute;n lo decretado por el Ministerio de Transporte sobre atenci&oacute;n al ciudadano en organismos de tr&aacute;nsito.&nbsp;<\/p>\n<p>Quienes ten&iacute;an agenda asignada para marzo, abril, mayo y junio podr&aacute;n ingresar a <strong><a href=\"http:\/\/www.medellin.gov.co\/movilidad\"><span style=\"color: #3366ff;\">www.medellin.gov.co\/movilidad<\/span><\/a><\/strong>, donde encontrar&aacute;n un cuestionario de competencias en seguridad vial y normatividad del C&oacute;digo Nacional de Tr&aacute;nsito, que deber&aacute;n realizar en l&iacute;nea.&nbsp;<\/p>\n<p>El subsecretario de Seguridad Vial y Control, Carlos Alberto Mar&iacute;n indic&oacute; que &ldquo;estamos aprovechando las ayudas tecnol&oacute;gicas con el fin de evitar grupos numerosos de personas en espacios cerrados, de ah&iacute; que reanudamos de manera virtual pensando en el bienestar y cuidado de todos los ciudadanos&rdquo;.&nbsp;<\/p>\n<p>Estos cursos aplican para ciudadanos que recibieron comparendos pedag&oacute;gicos en Medell&iacute;n y que ya ten&iacute;an una cita antes de comenzar la cuarentena.&nbsp;<\/p>\n<p>Tambi&eacute;n se reanudar&aacute;n las audiencias de tr&aacute;nsito y transporte y las diligencias asociadas al Registro Municipal de Conductores. Se except&uacute;an aquellos tr&aacute;mites que requieran del registro de inscripci&oacute;n por primera vez ante el RUNT, debido a que no se cuenta todav&iacute;a con la autenticaci&oacute;n digital y\/o f&iacute;sica de los usuarios. Una vez se habiliten se proceder&aacute; con su reactivaci&oacute;n.&nbsp;<\/p>\n<p>A la fecha est&aacute; activo el proceso de notificaci&oacute;n de las &oacute;rdenes de comparendos manuales y fotodetecciones.<\/p>\n<\/p>\n<p><span style=\"display:none\"\/><\/div>\n<div class=\"compartir\">Compartir en: <a title=\"\" href=\"http:\/\/www.facebook.com\/share.php?u=\" class=\"btCompartirFacebook btCompartir\" target=\"_blank\" rel=\"noopener\"><a title=\"\" href=\"http:\/\/twitter.com\/home?status=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirTwitter btCompartir\"\/><a title=\"\" href=\"whatsapp:\/\/send?text=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirWa btCompartir\"\/><\/div>\n<\/div>\n<p><script>try{comprobarImagen();fixBtnRedes();hitsMedellin();}catch(e){}<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cursos pedag\u00f3gicos de Movilidad se reactivar\u00e1n de manera virtual. Foto Alcald\u00eda de Medell\u00edn 2020-06-09 Cursos pedag\u00f3gicos de Movilidad se reactivar\u00e1n de manera virtual Por Prensa Alcald\u00eda de Medell\u00edn .: Las personas podr&aacute;n ingresar a www.medellin.gov.co\/movilidad &#8230;<\/p>\n","protected":false},"author":1,"featured_media":57428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[431,447],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/33623"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=33623"}],"version-history":[{"count":1,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/33623\/revisions"}],"predecessor-version":[{"id":36651,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/33623\/revisions\/36651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/57428"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=33623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=33623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=33623"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=33623"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=33623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}