{"id":34339,"date":"2020-02-17T00:00:00","date_gmt":"2020-02-17T05:00:00","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/saladeprensa\/noticias\/la-alcaldia-de-medellin-acompana-a-familias-venezolanas-que-ocupaban-un-edificio-abandonado-en-las-palmas\/"},"modified":"2022-03-27T22:29:29","modified_gmt":"2022-03-28T03:29:29","slug":"la-alcaldia-de-medellin-acompana-a-familias-venezolanas-que-ocupaban-un-edificio-abandonado-en-las-palmas","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/la-alcaldia-de-medellin-acompana-a-familias-venezolanas-que-ocupaban-un-edificio-abandonado-en-las-palmas\/","title":{"rendered":"La Alcald\u00eda de Medell\u00edn acompa\u00f1a a familias venezolanas que ocupaban un edificio abandonado en Las Palmas"},"content":{"rendered":"<div class=\"wrap contenido\">\n<div class=\"noticia\">\n<div class=\"imagen\">\n<div class=\"divContImageNoticia\" style=\"background-image:url('\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer\u00eda d\u00eda a d\u00eda 2020\/500_400\/20200217_Venezolanos2.jpg')\" rel=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer\u00eda d\u00eda a d\u00eda 2020\/500_400\/20200217_Venezolanos2.jpg\"><span style=\"display:none\"\/><\/div>\n<p>Vacio<\/p>\n<p>Vacio<\/p><\/div>\n<p class=\"fecha\"><span>2020-02-17<\/span><\/p>\n<p itemprop=\"name\">La Alcald\u00eda de Medell\u00edn acompa\u00f1a a familias venezolanas que ocupaban un edificio abandonado en Las Palmas<\/p>\n<p>Por Ver\u00f3nica Ospina Galeano<\/p>\n<div class=\"cuerpo\">\n<p><p>&#8211; Salud, vivienda y educaci&oacute;n forman parte de los beneficios que recibir&aacute;n los migrantes que estaban de forma irregular en este sitio.<br \/>&#8211; El edificio estaba sin terminar&nbsp; y tiene recomendaci&oacute;n del Departamento Administrativo de Gesti&oacute;n del Riesgo de Desastres -Dagrd para no ser habitado.<br \/>&#8211; El inmueble estaba ocupado por 21 familias conformadas por 62 personas.&nbsp;<\/p>\n<p>La Alcald&iacute;a de Medell&iacute;n sensibiliz&oacute; a 21 familias venezolanas que habitaban de forma irregular el edificio Soler Gardens, en Las Palmas, para que salieran voluntariamente del lugar, debido a las precarias condiciones en que resid&iacute;an all&iacute;.&nbsp;<\/p>\n<p><a target=\"_blank\" href=\"https:\/\/www.medellin.gov.co\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer&iacute;a d&iacute;a a d&iacute;a 2020\/20200217_Venezolanos1.jpeg\" rel=\"noopener\"><img src=\"https:\/\/www.medellin.gov.co\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer&iacute;a d&iacute;a a d&iacute;a 2020\/1000_450\/20200217_Venezolanos1.jpg\" width=\"100%\" alt=\"La Alcald&iacute;a de Medell&iacute;n acompa&ntilde;a a familias venezolanas que ocupaban un edificio abandonado en Las Palmas\" title=\"La Alcald&iacute;a de Medell&iacute;n acompa&ntilde;a a familias venezolanas que ocupaban un edificio abandonado en Las Palmas\"\/><\/a><\/p>\n<p>Del total de familias, 13 optaron por autoalbergarse con amigos y conocidos, dos recibieron alojamiento de parte de la Administraci&oacute;n Municipal y otras dos decidieron continuar viviendo en otro sitio por su propia cuenta. A las personas se les transportaron sus enseres y se les entreg&oacute; ayudas humanitarias.&nbsp;<\/p>\n<p>En total, 68 personas venezolanas conforman los n&uacute;cleos familiares, a los cuales se les acerc&oacute; oferta institucional en salud, vivienda y educaci&oacute;n y a todas se les dio acompa&ntilde;amiento.&nbsp;<\/p>\n<p>El retiro voluntario de estas personas se dio luego de acercamientos con la Alcald&iacute;a de Medell&iacute;n y otras entidades en los cuales se hicieron labores de caracterizaci&oacute;n y se determin&oacute; que el sitio representa riesgo para las familias, pues no se ha terminado de construir y tiene recomendaci&oacute;n del Departamento Administrativo de Gesti&oacute;n del Riesgo de Desastres para no ser habitado.&nbsp;<\/p>\n<p>La Administraci&oacute;n Municipal realiz&oacute; varias visitas a la edificaci&oacute;n, en enero y febrero de este a&ntilde;o, y adelant&oacute; procesos de sensibilizaci&oacute;n con los hogares sobre el riesgo de seguir viviendo en el edificio, el cual hab&iacute;a sido acondicionado por ellos mismos con inapropiadas conexiones el&eacute;ctricas y alcantarillado no convencional.&nbsp;<\/p>\n<p>La mayor&iacute;a de los 25 ni&ntilde;os y adolescentes pertenecientes a estas familias estaban desescolarizados y ahora se beneficiar&aacute;n con oferta educativa.&nbsp;<\/p>\n<p>Adem&aacute;s, la mayor parte de las personas se encuentran en estado de migraci&oacute;n irregular en el pa&iacute;s, por lo cual se les da asesor&iacute;a para que tramiten el Permiso Especial de Permanencia. Este les facilita acceder&nbsp; a la oferta institucional.&nbsp;<\/p>\n<p>El proceso cont&oacute; con el apoyo de la ONG Mercy Corps y el Alto Comisionado de las Naciones Unidas para los Refugiados -Acnur.&nbsp;<\/p>\n<\/p>\n<p><span style=\"display:none\"\/><\/div>\n<div class=\"compartir\">Compartir en: <a title=\"\" href=\"http:\/\/www.facebook.com\/share.php?u=\" class=\"btCompartirFacebook btCompartir\" target=\"_blank\" rel=\"noopener\"><a title=\"\" href=\"http:\/\/twitter.com\/home?status=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirTwitter btCompartir\"\/><a title=\"\" href=\"whatsapp:\/\/send?text=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirWa btCompartir\"\/><\/div>\n<\/div>\n<p><script>try{comprobarImagen();fixBtnRedes();hitsMedellin();}catch(e){}<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vacio Vacio 2020-02-17 La Alcald\u00eda de Medell\u00edn acompa\u00f1a a familias venezolanas que ocupaban un edificio abandonado en Las Palmas Por Ver\u00f3nica Ospina Galeano &#8211; Salud, vivienda y educaci&oacute;n forman parte de los beneficios que recibir&aacute;n &#8230;<\/p>\n","protected":false},"author":1,"featured_media":58123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[451,440,435],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/34339"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=34339"}],"version-history":[{"count":1,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/34339\/revisions"}],"predecessor-version":[{"id":37366,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/34339\/revisions\/37366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/58123"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=34339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=34339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=34339"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=34339"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=34339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}