{"id":34962,"date":"2020-02-14T00:00:00","date_gmt":"2020-02-14T05:00:00","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/saladeprensa\/noticias\/500-jovenes-aportaron-sus-propuestas-para-el-plan-de-desarrollo-medellin-futuro\/"},"modified":"2022-03-27T22:54:47","modified_gmt":"2022-03-28T03:54:47","slug":"500-jovenes-aportaron-sus-propuestas-para-el-plan-de-desarrollo-medellin-futuro","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/500-jovenes-aportaron-sus-propuestas-para-el-plan-de-desarrollo-medellin-futuro\/","title":{"rendered":"500 j\u00f3venes aportaron sus propuestas para el Plan de Desarrollo Medell\u00edn Futuro"},"content":{"rendered":"<div class=\"wrap contenido\">\n<div class=\"noticia\">\n<div class=\"imagen\">\n<div class=\"divContImageNoticia\" style=\"background-image:url('\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer\u00eda d\u00eda a d\u00eda 2020\/500_400\/20200213_PD_Jovenes3.jpg')\" rel=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer\u00eda d\u00eda a d\u00eda 2020\/500_400\/20200213_PD_Jovenes3.jpg\"><span style=\"display:none\"\/><\/div>\n<p>500 j\u00f3venes aportaron sus propuestas para el Plan de Desarrollo Medell\u00edn Futuro.<\/p>\n<p>Foto Alcald\u00eda de Medell\u00edn<\/p><\/div>\n<p class=\"fecha\"><span>2020-02-14<\/span><\/p>\n<p itemprop=\"name\">500 j\u00f3venes aportaron sus propuestas para el Plan de Desarrollo Medell\u00edn Futuro<\/p>\n<p>Por Prensa Alcald\u00eda de Medell\u00edn<\/p>\n<div class=\"cuerpo\">\n<p><p>&#8211; Este viernes concluyen los encuentros juveniles que agruparon a 42 instituciones educativas y doce universidades.<br \/>&#8211; Fueron cinco jornadas en el Centro de Innovaci&oacute;n del Maestro, el Instituto Tecnol&oacute;gico Metropolitano,&nbsp; la Universidad de Antioquia, el Censa y la Universidad Eafit.<\/p>\n<p>Con las propuestas de 500 j&oacute;venes, Medell&iacute;n avanza en la construcci&oacute;n del Plan de Desarrollo m&aacute;s participativo de su historia. Esta tarde concluyen en el Centro de Innovaci&oacute;n del Maestro (MOVA) los encuentros juveniles, que han abordado tem&aacute;ticas como educaci&oacute;n, promoci&oacute;n y prevenci&oacute;n de la salud mental, optimizaci&oacute;n de procesos a nivel tecnol&oacute;gico y virtual, y oferta cultural y art&iacute;stica.&nbsp;<\/p>\n<div class=\"programas todosProgramas contAdicionalHome\">\n<ul class=\"categoriaPrincipal categoriaPrincipal1 col3 ulAjustada listaGenerica-NoBorde-NoTam\">\n<li><a target=\"_blank\" href=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer&iacute;a d&iacute;a a d&iacute;a 2020\/20200213_PD_Jovenes4.jpeg\" title=\"500 j&oacute;venes aportaron sus propuestas para el Plan de Desarrollo Medell&iacute;n Futuro\" rel=\"noopener\"><img src=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer&iacute;a d&iacute;a a d&iacute;a 2020\/500_400\/20200213_PD_Jovenes4.jpg\" alt=\"500 j&oacute;venes aportaron sus propuestas para el Plan de Desarrollo Medell&iacute;n Futuro\" title=\"500 j&oacute;venes aportaron sus propuestas para el Plan de Desarrollo Medell&iacute;n Futuro\"\/><\/a><\/li>\n<li><a target=\"_blank\" href=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer&iacute;a d&iacute;a a d&iacute;a 2020\/20200213_PD_Jovenes2.jpeg\" title=\"500 j&oacute;venes aportaron sus propuestas para el Plan de Desarrollo Medell&iacute;n Futuro\" rel=\"noopener\"><img src=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer&iacute;a d&iacute;a a d&iacute;a 2020\/500_400\/20200213_PD_Jovenes2.jpg\" alt=\"500 j&oacute;venes aportaron sus propuestas para el Plan de Desarrollo Medell&iacute;n Futuro\" title=\"500 j&oacute;venes aportaron sus propuestas para el Plan de Desarrollo Medell&iacute;n Futuro\"\/><\/a><a target=\"_blank\" href=\"\/irj\/go\/km\/docs\/pccdesign\/medellin\/Temas\/Cultura\/Programas\/Shared Content\/Imagenes\/2018\/CiudadanoscomoVos2.jpg\" rel=\"noopener\"><\/a><\/li>\n<li><a target=\"_blank\" href=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer&iacute;a d&iacute;a a d&iacute;a 2020\/20200213_PD_Jovenes1.jpeg\" title=\"500 j&oacute;venes aportaron sus propuestas para el Plan de Desarrollo Medell&iacute;n Futuro\" rel=\"noopener\"><img src=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer&iacute;a d&iacute;a a d&iacute;a 2020\/500_400\/20200213_PD_Jovenes1.jpg\" alt=\"500 j&oacute;venes aportaron sus propuestas para el Plan de Desarrollo Medell&iacute;n Futuro\" title=\"500 j&oacute;venes aportaron sus propuestas para el Plan de Desarrollo Medell&iacute;n Futuro\"\/><\/a><a target=\"_blank\" href=\"\/irj\/go\/km\/docs\/pccdesign\/medellin\/Temas\/Cultura\/Programas\/Shared Content\/Imagenes\/2018\/CiudadanoscomoVos3.jpg\" rel=\"noopener\"><\/a><\/li>\n<\/ul><\/div>\n<p>&ldquo;Cerramos con un balance muy satisfactorio. Nunca en Medell&iacute;n se hab&iacute;a realizado un espacio de encuentro donde los j&oacute;venes pudieran incidir de una forma tan importante en la construcci&oacute;n del Plan de Desarrollo&rdquo;, dijo el secretario de Participaci&oacute;n Ciudadana, Juan Pablo Ram&iacute;rez.&nbsp;<\/p>\n<p>Las propuestas recibidas en estos escenarios complementan los encuentros territoriales, que se realizaron desde el 2 de febrero en las comunas y corregimientos.&nbsp;<\/p>\n<p>&ldquo;Hay una intenci&oacute;n muy fuerte de volver a creer en la ciudad, en la democracia y ser parte de la soluci&oacute;n&rdquo;, expres&oacute; Daniel Gaviria, facilitador de los talleres.&nbsp;<\/p>\n<p>Una de las participantes fue Estefan&iacute;a Arango, estudiante de Derecho, quien expres&oacute; su complacencia de que &ldquo;hayan incluido a la poblaci&oacute;n acad&eacute;mica para que todas las ideas que siempre nos planteamos salgan de las aulas&rdquo;.&nbsp;<\/p>\n<p>Las jornadas, organizadas por las secretar&iacute;as de Participaci&oacute;n Ciudadana, Juventud y Educaci&oacute;n, contaron con las mesas tem&aacute;ticas Valle del Software, Ecociudad,&nbsp; Recuperemos lo Social, Transformaci&oacute;n Educativa y Gobernanza y Gobernabilidad, seg&uacute;n el Programa de Gobierno del alcalde Daniel Quintero Calle.<\/p>\n<\/p>\n<p><span style=\"display:none\"\/><\/div>\n<div class=\"compartir\">Compartir en: <a title=\"\" href=\"http:\/\/www.facebook.com\/share.php?u=\" class=\"btCompartirFacebook btCompartir\" target=\"_blank\" rel=\"noopener\"><a title=\"\" href=\"http:\/\/twitter.com\/home?status=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirTwitter btCompartir\"\/><a title=\"\" href=\"whatsapp:\/\/send?text=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirWa btCompartir\"\/><\/div>\n<\/div>\n<p><script>try{comprobarImagen();fixBtnRedes();hitsMedellin();}catch(e){}<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>500 j\u00f3venes aportaron sus propuestas para el Plan de Desarrollo Medell\u00edn Futuro. Foto Alcald\u00eda de Medell\u00edn 2020-02-14 500 j\u00f3venes aportaron sus propuestas para el Plan de Desarrollo Medell\u00edn Futuro Por Prensa Alcald\u00eda de Medell\u00edn &#8211; &#8230;<\/p>\n","protected":false},"author":1,"featured_media":59267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[29,12],"tags":[435,450],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/34962"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=34962"}],"version-history":[{"count":1,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/34962\/revisions"}],"predecessor-version":[{"id":46683,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/34962\/revisions\/46683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/59267"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=34962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=34962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=34962"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=34962"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=34962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}