{"id":35255,"date":"2020-06-08T00:00:00","date_gmt":"2020-06-08T05:00:00","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/saladeprensa\/noticias\/desarmando-la-violencia-en-lo-cotidiano-es-la-propuesta-de-la-semana-de-prevencion-de-la-violencia-armada\/"},"modified":"2022-03-27T23:00:30","modified_gmt":"2022-03-28T04:00:30","slug":"desarmando-la-violencia-en-lo-cotidiano-es-la-propuesta-de-la-semana-de-prevencion-de-la-violencia-armada","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/desarmando-la-violencia-en-lo-cotidiano-es-la-propuesta-de-la-semana-de-prevencion-de-la-violencia-armada\/","title":{"rendered":"\u201cDesarmando la violencia en lo cotidiano\u201d es la propuesta de la Semana de Prevenci\u00f3n de la Violencia Armada"},"content":{"rendered":"<div class=\"wrap contenido\">\n<div class=\"noticia\">\n<div class=\"imagen\">\n<div class=\"divContImageNoticia\" style=\"background-image:url('\/irj\/go\/km\/docs\/pccdesign\/medellin\/Temas\/Seguridad\/Noticias\/Shared Content\/Imagenes\/2019\/20180806_NoViolencia.jpg')\" rel=\"\/irj\/go\/km\/docs\/pccdesign\/medellin\/Temas\/Seguridad\/Noticias\/Shared Content\/Imagenes\/2019\/20180806_NoViolencia.jpg\"><span style=\"display:none\"\/><\/div>\n<p>Foto de archivo.<\/p>\n<p>Alcald\u00eda de Medell\u00edn<\/p><\/div>\n<p class=\"fecha\"><span>2020-06-08<\/span><\/p>\n<p itemprop=\"name\">\u201cDesarmando la violencia en lo cotidiano\u201d es la propuesta de la Semana de Prevenci\u00f3n de la Violencia Armada<\/p>\n<p>Por Stephen Arboleda.<\/p>\n<div class=\"cuerpo\">\n<p><p>.: Esta es la edici&oacute;n n&uacute;mero 12 de la <i>Semana de Prevenci&oacute;n de la Violencia Armada<\/i> con programaci&oacute;n especial para la ciudad.<br \/>.: Por primera vez, el evento se da en medio de una reducci&oacute;n hist&oacute;rica de homicidios y bajo la premisa <i>&ldquo;Todas las vidas nos importan, todas las vidas son iguales&rdquo;<\/i>.<\/p>\n<p>Entre el 8 y el 12 de junio se realizar&aacute; la <i>Semana de Prevenci&oacute;n de la Violencia Armada<\/i>, que en su edici&oacute;n n&uacute;mero 12 se cumplir&aacute; de manera especial, debido a las condiciones de la pandemia y a cifras hist&oacute;ricas de reducci&oacute;n de la violencia armada en el territorio. Los homicidios bajaron 50 % y todos los delitos de alto impacto hasta un 80 %.<\/p>\n<p>Con el mensaje <i>&ldquo;desarmando la violencia en lo cotidiano&rdquo;<\/i> se invita a la ciudadan&iacute;a a suprimir la tenencia y el uso de armas. Igualmente, a crear lazos de solidaridad, de respeto con ellos mismos, con la ciudad y con los otros, mediante el desarme de palabras y acciones violentas que dificultan la construcci&oacute;n de escenarios de convivencia.<\/p>\n<p>Esta semana se realizar&aacute;n dos <i>Encuentros por el Desarme<\/i>. El primero de ellos ser&aacute; el martes 9 de junio, a las 4.00 p. m., para reconocer el trabajo y experiencia de algunas organizaciones sociales, que a trav&eacute;s de proyectos art&iacute;sticos y culturales han logrado vincular a j&oacute;venes en situaci&oacute;n de vulnerabilidad, permiti&eacute;ndoles as&iacute; construir proyectos de vida sostenibles y ser actores claves en los procesos de transformaci&oacute;n de sus entornos cercanos y territorios.&nbsp;<\/p>\n<p>La segunda actividad ser&aacute; el viernes 12 de junio, a las 8:00 a. m., para conocer y reconocer experiencias positivas que han tenido lugar en pa&iacute;ses amigos, que tambi&eacute;n motivan a la ciudadan&iacute;a al desarme y a dejar las acciones violentas como primer paso hacia el fortalecimiento del tejido social.<\/p>\n<p>Ambos encuentros se transmitir&aacute;n por el Facebook Live de la Secretar&iacute;a de Seguridad y Convivencia como una oportunidad para reflexionar sobre la importancia y necesidad de valorar, respetar y preservar la vida por encima de cualquier otro asunto.&nbsp;<\/p>\n<p>La <i>Semana de Prevenci&oacute;n de la Violencia Armada<\/i> se realiza cada a&ntilde;o por Acuerdo Municipal del 6 de mayo de 2007.<\/p>\n<\/p>\n<p><span style=\"display:none\"\/><\/div>\n<div class=\"compartir\">Compartir en: <a title=\"\" href=\"http:\/\/www.facebook.com\/share.php?u=\" class=\"btCompartirFacebook btCompartir\" target=\"_blank\" rel=\"noopener\"><a title=\"\" href=\"http:\/\/twitter.com\/home?status=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirTwitter btCompartir\"\/><a title=\"\" href=\"whatsapp:\/\/send?text=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirWa btCompartir\"\/><\/div>\n<\/div>\n<p><script>try{comprobarImagen();fixBtnRedes();hitsMedellin();}catch(e){}<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto de archivo. Alcald\u00eda de Medell\u00edn 2020-06-08 \u201cDesarmando la violencia en lo cotidiano\u201d es la propuesta de la Semana de Prevenci\u00f3n de la Violencia Armada Por Stephen Arboleda. .: Esta es la edici&oacute;n n&uacute;mero 12 &#8230;<\/p>\n","protected":false},"author":1,"featured_media":59514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20,21],"tags":[455],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/35255"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=35255"}],"version-history":[{"count":1,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/35255\/revisions"}],"predecessor-version":[{"id":47174,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/35255\/revisions\/47174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/59514"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=35255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=35255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=35255"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=35255"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=35255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}