{"id":35656,"date":"2021-02-08T00:00:00","date_gmt":"2021-02-08T05:00:00","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/saladeprensa\/noticias\/este-miercoles-inicia-la-alternancia-en-las-instituciones-educativas-oficiales-de-medellin\/"},"modified":"2022-03-27T23:11:07","modified_gmt":"2022-03-28T04:11:07","slug":"este-miercoles-inicia-la-alternancia-en-las-instituciones-educativas-oficiales-de-medellin","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/este-miercoles-inicia-la-alternancia-en-las-instituciones-educativas-oficiales-de-medellin\/","title":{"rendered":"Este mi\u00e9rcoles inicia la alternancia en las instituciones educativas oficiales de Medell\u00edn"},"content":{"rendered":"<div class=\"wrap contenido\">\n<div class=\"noticia\">\n<div class=\"imagen\">\n<div class=\"divContImageNoticia input_plantilla input_background\" data-input=\"fotografia\" ruta=\"\/galerias\/Imagenes\/Galer\u00eda d\u00eda a d\u00eda 2021\/500_400\/20210208-Alternancia-Educativa-1.jpg\" fotografo=\"Foto Alcald\u00eda de Medell\u00edn\" descripcion=\"Este mi\u00e9rcoles inicia la alternancia en las instituciones educativas oficiales de Medell\u00edn.\" style=\"background-image:url('\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer\u00eda d\u00eda a d\u00eda 2021\/500_400\/20210208-Alternancia-Educativa-1.jpg')\"><\/div>\n<p class=\"pMetaDesc\">Foto: Este mi\u00e9rcoles inicia la alternancia en las instituciones educativas oficiales de Medell\u00edn.<\/p>\n<p class=\"pMetaFotografo\">Fot\u00f3grafo: Foto Alcald\u00eda de Medell\u00edn<\/p>\n<\/div>\n<p class=\"fecha\"><span class=\"input_plantilla input_text\" data-input=\"fecha\">2021-02-08<\/span><\/p>\n<p itemprop=\"name\" class=\"input_plantilla input_text\" data-input=\"titulo\">Este mi\u00e9rcoles inicia la alternancia en las instituciones educativas oficiales de Medell\u00edn<\/p>\n<p class=\"input_plantilla input_text\" data-input=\"autor\">Por Eduar Rend\u00f3n<\/p>\n<div class=\"cuerpo input_plantilla input_area\" data-input=\"contenido\">\n<p>.: La Alternancia Educativa se implementar\u00e1 de forma gradual y segura.&nbsp;<\/p>\n<p>.: Los 23 establecimientos que participaron en el plan piloto del modelo durante 2020 ser\u00e1n los primeros en abrir sus aulas.<\/p>\n<p>&nbsp;<a href=\"\/irj\/go\/km\/docs\/galerias\/Audios\/Audios d\u00eda a d\u00eda 2021\/20210208-Alternancia-Educativa-01.mp3\" class=\"aContEnlace audio\" download=\"\" data-mce-href=\"\/irj\/go\/km\/docs\/galerias\/Audios\/Audios d\u00eda a d\u00eda 2021\/20210208-Alternancia-Educativa-01.mp3\"><span>Palabras de Alexandra Agudelo, secretaria de Educaci\u00f3n.<\/span><span><\/span><span>2583 Kb<\/span><\/a><\/p>\n<p><a href=\"\/irj\/go\/km\/docs\/galerias\/Audios\/Audios d\u00eda a d\u00eda 2021\/20210208-Alternancia-Educativa-02.mp3\" class=\"aContEnlace audio\" download=\"\" data-mce-href=\"\/irj\/go\/km\/docs\/galerias\/Audios\/Audios d\u00eda a d\u00eda 2021\/20210208-Alternancia-Educativa-02.mp3\"><span>Palabras de Eduardo Luis L\u00f3pez Guzm\u00e1n, Rector de la I.E. Pablo Neruda<\/span><span><\/span><span>610 Kb<\/span><\/a><\/p>\n<p>La Alcald\u00eda de Medell\u00edn aplicar\u00e1 la Alternancia Educativa en las instituciones oficiales a partir del pr\u00f3ximo mi\u00e9rcoles, 10 de febrero, y de esta manera se suma a los colegios privados que ya ven\u00edan trabajando bajo este modelo.&nbsp;<\/p>\n<p>La decisi\u00f3n se tom\u00f3 debido a condiciones favorables en la ciudad como la disminuci\u00f3n en el porcentaje de ocupaci\u00f3n en las Unidades de Cuidados Intensivos y el nivel de contagios de coronavirus.&nbsp;<\/p>\n<p><a data-mce-href=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer%C3%ADa%20d%C3%ADa%20a%20d%C3%ADa%202021\/20210208-Alternancia-Educativa-2.jpg\" href=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer%C3%ADa%20d%C3%ADa%20a%20d%C3%ADa%202021\/20210208-Alternancia-Educativa-2.jpg\" title=\"Este mi\u00e9rcoles inicia la alternancia en las instituciones educativas oficiales de Medell\u00edn\" target=\"_blank\" rel=\"noopener\"><img src=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer%C3%ADa%20d%C3%ADa%20a%20d%C3%ADa%202021\/1000_450\/20210208-Alternancia-Educativa-2.jpg\" alt=\"Este mi\u00e9rcoles inicia la alternancia en las instituciones educativas oficiales de Medell\u00edn\" width=\"100%\"><\/a><br data-mce-bogus=\"1\"><\/p>\n<p>\u201c<em>Estaremos en un regreso gradual, progresivo y seguro; no todas las instituciones educativas entrar\u00e1n de una vez, cada una de ellas con su gobierno escolar y consejo directivo se han venido preparando y organizando el proceso para regresar en alternancia<\/em>\u201d, asegur\u00f3 la secretaria de Educaci\u00f3n, Alexandra Agudelo Ruiz.&nbsp;<\/p>\n<p>La Alternancia Educativa tendr\u00e1 dos fases, cada una de ellas con tres etapas, as\u00ed:&nbsp;<\/p>\n<p>La fase uno en su primera etapa inicia este 10 de febrero y contempla el regreso a las aulas de los 23 establecimientos educativos, 12 colegios p\u00fablicos y 11 de cobertura que terminaron el calendario acad\u00e9mico 2020 con ese modelo.&nbsp;<\/p>\n<p>La etapa dos ser\u00e1 el 15 de febrero, cuando los alumnos retornar\u00e1n a las instituciones que hasta la fecha tienen protocolo de bioseguridad aprobado y plan piloto cumplido. El 22 de febrero comenzar\u00e1 la etapa tres en la que se sumar\u00e1n los colegios que sean autorizados por las secretar\u00edas de Salud y Educaci\u00f3n de Medell\u00edn.&nbsp;<\/p>\n<p>La secretaria de Educaci\u00f3n afirm\u00f3 \u201c<em>nosotros desde Educaci\u00f3n no tomamos ninguna decisi\u00f3n si no es de la mano de la Secretar\u00eda de Salud. Ellos nos dan un reporte positivo sobre la disminuci\u00f3n de contagios en Medell\u00edn, al igual que en la ocupaci\u00f3n de las camas UCI en la ciudad para regresar en alternancia<\/em>\u201d.&nbsp;<\/p>\n<p>En la segunda fase, las etapas uno y dos, que empezar\u00e1n el 1 y 8 de marzo respectivamente, la alternancia se dar\u00e1 a medida que las instituciones aprueben los protocolos de bioseguridad y cumplan el plan piloto. Para el 15 de marzo est\u00e1 contemplada la etapa tres en la que todos los establecimientos escolares de la ciudad deber\u00e1n estar en Alternancia Educativa.<\/p>\n<p>La Secretar\u00eda de Educaci\u00f3n, con el fin de proteger la salud de los estudiantes, ha adecuado y dotado 327 sedes con elementos de bioseguridad como term\u00f3metros, tapetes, alcohol, amonio cuaternario, gel antibacterial, tapabocas, lavamanos port\u00e1tiles y se\u00f1al\u00e9tica, y as\u00ed garantizar el cumplimiento de los protocolos y el distanciamiento social.&nbsp;<\/p>\n<p>Actualmente hay 429 planteles educativos con protocolos de bioseguridad aprobados: 112 oficiales, 91 privados, 25 de cobertura, 135 preescolares, 64 de Educaci\u00f3n para el Trabajo y el Desarrollo Humano y 2 confesiones religiosas.<\/p>\n<\/div>\n<div class=\"compartir\">Compartir en:<a title=\"\" href=\"http:\/\/www.facebook.com\/share.php?u=\" class=\"btCompartirFacebook btCompartir\" target=\"_blank\" rel=\"noopener\"><\/a><a title=\"\" href=\"http:\/\/twitter.com\/home?status=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirTwitter btCompartir\"><\/a><a title=\"\" href=\"whatsapp:\/\/send?text=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirWa btCompartir\"><\/a><\/div>\n<\/div>\n<p><script>try{comprobarImagen();fixBtnRedes();hitsMedellin();}catch(e){}<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Este mi\u00e9rcoles inicia la alternancia en las instituciones educativas oficiales de Medell\u00edn. Fot\u00f3grafo: Foto Alcald\u00eda de Medell\u00edn 2021-02-08 Este mi\u00e9rcoles inicia la alternancia en las instituciones educativas oficiales de Medell\u00edn Por Eduar Rend\u00f3n .: &#8230;<\/p>\n","protected":false},"author":1,"featured_media":59890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[431],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/35656"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=35656"}],"version-history":[{"count":1,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/35656\/revisions"}],"predecessor-version":[{"id":47890,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/35656\/revisions\/47890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/59890"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=35656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=35656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=35656"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=35656"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=35656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}