{"id":427739,"date":"2025-07-12T10:18:15","date_gmt":"2025-07-12T15:18:15","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/?p=427739"},"modified":"2025-07-12T10:18:15","modified_gmt":"2025-07-12T15:18:15","slug":"alcaldia-de-medellin-extendio-el-plazo-de-licitacion-para-la-ampliacion-en-la-avenida-34-con-la-loma-los-gonzalez","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/alcaldia-de-medellin-extendio-el-plazo-de-licitacion-para-la-ampliacion-en-la-avenida-34-con-la-loma-los-gonzalez\/","title":{"rendered":"Alcald\u00eda de Medell\u00edn extendi\u00f3 el plazo de licitaci\u00f3n para la ampliaci\u00f3n en la avenida 34 con la Loma Los Gonz\u00e1lez"},"content":{"rendered":"<ul>\n<li>Las empresas interesadas en ejecutar esta obra que supera los $31.000 millones, tienen plazo hasta el 18 de julio para presentar sus propuestas.<\/li>\n<\/ul>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n\t<div class=\"wp-playlist wp-audio-playlist wp-playlist-light\">\n\t\t\t<div class=\"wp-playlist-current-item\"><\/div>\n\t\t<audio controls=\"controls\" preload=\"none\" width=\"640\"\n\t\t\t><\/audio>\n\t<div class=\"wp-playlist-next\"><\/div>\n\t<div class=\"wp-playlist-prev\"><\/div>\n\t<noscript>\n\t<ol>\n\t\t<li><a href='https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Declaraciones-del-gerente-EDU-Emiro-Valdes-Lopez.mp3'>Declaraciones del gerente EDU, Emiro Vald\u00e9s\u00a0L\u00f3pez<\/a><\/li><li><a href='https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Declaraciones-de-la-directora-del-Fondo-de-Valorizacion-de-Medellin-Angelica-Maria-Arias-Loza.mp3'>Declaraciones de la directora del Fondo de Valorizaci\u00f3n de Medell\u00edn, Ang\u00e9lica Mar\u00eda\u00a0Arias\u00a0Loza<\/a><\/li>\t<\/ol>\n\t<\/noscript>\n\t<script type=\"application\/json\" class=\"wp-playlist-script\">{\"type\":\"audio\",\"tracklist\":true,\"tracknumbers\":true,\"images\":true,\"artists\":true,\"tracks\":[{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Declaraciones-del-gerente-EDU-Emiro-Valdes-Lopez.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"Declaraciones del gerente EDU, Emiro Vald\\u00e9s\\u00a0L\\u00f3pez\",\"caption\":\"\",\"description\":\"\\u00abDeclaraciones del gerente EDU, Emiro Vald\\u00e9s\\u00a0L\\u00f3pez\\u00bb.\",\"meta\":{\"length_formatted\":\"1:15\"},\"image\":{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-includes\\\/images\\\/media\\\/audio.png\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-includes\\\/images\\\/media\\\/audio.png\",\"width\":48,\"height\":64}},{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Declaraciones-de-la-directora-del-Fondo-de-Valorizacion-de-Medellin-Angelica-Maria-Arias-Loza.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"Declaraciones de la directora del Fondo de Valorizaci\\u00f3n de Medell\\u00edn, Ang\\u00e9lica Mar\\u00eda\\u00a0Arias\\u00a0Loza\",\"caption\":\"\",\"description\":\"\\u00abDeclaraciones de la directora del Fondo de Valorizaci\\u00f3n de Medell\\u00edn, Ang\\u00e9lica Mar\\u00eda\\u00a0Arias\\u00a0Loza\\u00bb.\",\"meta\":{\"length_formatted\":\"0:52\"},\"image\":{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-includes\\\/images\\\/media\\\/audio.png\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-includes\\\/images\\\/media\\\/audio.png\",\"width\":48,\"height\":64}}]}<\/script>\n<\/div>\n\t\n<p>La Administraci\u00f3n Distrital, a trav\u00e9s de la Empresa de Desarrollo Urbano (EDU), ampli\u00f3 hasta el pr\u00f3ximo viernes 18 de julio, el plazo de la invitaci\u00f3n abierta para adjudicar las obras de ampliaci\u00f3n de la avenida 34 con la Loma de Los Gonz\u00e1lez, uno de los proyectos de valorizaci\u00f3n m\u00e1s importantes para la movilidad en la comuna 14-El Poblado.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-large wp-image-427745\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-calle-Medellin-1024x682.jpg\" alt=\"Imagen calle Medell\u00edn\" width=\"1024\" height=\"682\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-calle-Medellin-1024x682.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-calle-Medellin-300x200.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-calle-Medellin-150x100.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-calle-Medellin-768x512.jpg 768w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-calle-Medellin.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>La convocatoria estar\u00e1 abierta en la plataforma Secop II a trav\u00e9s del enlace: <a href=\"https:\/\/community.secop.gov.co\/Public\/Tendering\/OpportunityDetail\/Index?noticeUID=CO1.NTC.8350793&amp;isFromPublicArea=True&amp;isModal=False.\" target=\"_blank\" rel=\"noopener\">https:\/\/community.secop.gov.co\/Public\/Tendering\/OpportunityDetail\/Index?noticeUID=CO1.NTC.8350793&amp;isFromPublicArea=True&amp;isModal=False.<\/a><\/p>\n<p>Frente a la adjudicaci\u00f3n de la interventor\u00eda, 30 empresas manifestaron su inter\u00e9s y 10 de ellas fueron seleccionadas en sorteo, para presentar propuesta definitiva.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-large wp-image-427752\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-Medellin-1024x576.jpg\" alt=\"Imagen panor\u00e1mica Medell\u00edn\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-Medellin-1024x576.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-Medellin-300x169.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-Medellin-150x84.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-Medellin-768x432.jpg 768w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-Medellin.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>La primera etapa de este contrato que supera los $31.000 millones incluyendo obra m\u00e1s interventor\u00eda, contempla la construcci\u00f3n de cerca de 500 metros de doble calzada, tres puentes sobre la quebrada La Volcana, la canalizaci\u00f3n de agua en la quebrada La Sucia, y obras de estabilizaci\u00f3n y urbanismo.<\/p>\n<p>Esta intervenci\u00f3n, que tiene un plazo de ejecuci\u00f3n de 16 meses a partir de la firma del acta de inicio, cuenta con todos los estudios y dise\u00f1os aprobados. Adem\u00e1s de licencia y el permiso de aprovechamiento forestal.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-large wp-image-427753\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-1-1024x576.jpg\" alt=\"Imagen panor\u00e1mica\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-1-1024x576.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-1-300x169.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-1-150x84.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-1-768x432.jpg 768w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2025\/07\/Imagen-panoramica-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>La segunda etapa del proyecto contempla la construcci\u00f3n de los pasos a desnivel en La Loma de Los Gonz\u00e1lez y del proyecto habitacional de reasentamiento en entorno para las familias del sector de El Chispero, cuyos predios fueron requeridos para la obra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las empresas interesadas en ejecutar esta obra que supera los $31.000 millones, tienen plazo hasta el 18 de julio para presentar sus propuestas. La Administraci\u00f3n Distrital, a trav\u00e9s de la Empresa de Desarrollo Urbano (EDU), &#8230;<\/p>\n","protected":false},"author":97,"featured_media":427749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[17],"tags":[],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/427739"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=427739"}],"version-history":[{"count":1,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/427739\/revisions"}],"predecessor-version":[{"id":427754,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/427739\/revisions\/427754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/427749"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=427739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=427739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=427739"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=427739"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=427739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}