{"id":529896,"date":"2026-05-13T16:08:54","date_gmt":"2026-05-13T21:08:54","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/?p=529896"},"modified":"2026-05-13T16:08:54","modified_gmt":"2026-05-13T21:08:54","slug":"avanza-la-recuperacion-de-los-escenarios-deportivos-de-medellin-con-intervenciones-en-el-polvorin-y-barrio-cristobal","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/avanza-la-recuperacion-de-los-escenarios-deportivos-de-medellin-con-intervenciones-en-el-polvorin-y-barrio-cristobal\/","title":{"rendered":"Avanza la recuperaci\u00f3n de los escenarios deportivos de Medell\u00edn con intervenciones en El Polvor\u00edn y Barrio Crist\u00f3bal"},"content":{"rendered":"<ul>\n<li>Hasta la primera semana de mayo, la Administraci\u00f3n Distrital entreg\u00f3 397 escenarios deportivos recuperados y modernizados en diferentes comunas y corregimientos.<\/li>\n<li>Adem\u00e1s, nueve nuevos escenarios ya iniciaron obras y otros nueve comenzar\u00e1n intervenci\u00f3n pr\u00f3ximamente, como parte del plan de mejoramiento de la infraestructura deportiva.<\/li>\n<\/ul>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n\t<div class=\"wp-playlist wp-audio-playlist wp-playlist-light\">\n\t\t\t<div class=\"wp-playlist-current-item\"><\/div>\n\t\t<audio controls=\"controls\" preload=\"none\" width=\"640\"\n\t\t\t><\/audio>\n\t<div class=\"wp-playlist-next\"><\/div>\n\t<div class=\"wp-playlist-prev\"><\/div>\n\t<noscript>\n\t<ol>\n\t\t<li><a href='https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Declaraciones-del-director-del-Inder-Eduardo-Silva-Meluk.mp3'>Declaraciones del director del Inder, Eduardo Silva Meluk<\/a><\/li>\t<\/ol>\n\t<\/noscript>\n\t<script type=\"application\/json\" class=\"wp-playlist-script\">{\"type\":\"audio\",\"tracklist\":true,\"tracknumbers\":true,\"images\":true,\"artists\":true,\"tracks\":[{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Declaraciones-del-director-del-Inder-Eduardo-Silva-Meluk.mp3\",\"type\":\"audio\\\/mpeg\",\"title\":\"Declaraciones del director del Inder, Eduardo Silva Meluk\",\"caption\":\"\",\"description\":\"\\u00abDeclaraciones del director del Inder, Eduardo Silva Meluk\\u00bb. \",\"meta\":{\"genre\":\"Blues\",\"length_formatted\":\"1:09\"},\"image\":{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-includes\\\/images\\\/media\\\/audio.png\",\"width\":48,\"height\":64},\"thumb\":{\"src\":\"https:\\\/\\\/www.medellin.gov.co\\\/es\\\/wp-includes\\\/images\\\/media\\\/audio.png\",\"width\":48,\"height\":64}}]}<\/script>\n<\/div>\n\t\n<p>La Alcald\u00eda de Medell\u00edn contin\u00faa avanzando en el fortalecimiento y recuperaci\u00f3n de la infraestructura deportiva de la ciudad, con obras prioritarias solicitadas por las comunidades, entre ellas en las canchas de El Polvor\u00edn y Barrio Crist\u00f3bal, donde actualmente se ejecutan intervenciones integrales.<\/p>\n<p>En el caso de la cancha de El Polvor\u00edn, en la comuna 6-Doce de Octubre, el proyecto fue adjudicado el pasado 29 de abril, por un valor superior a los $3.416 millones. Actualmente, el contrato se encuentra en etapa de legalizaci\u00f3n para dar inicio a las obras que permitir\u00e1n mejorar las condiciones del escenario y ampliar las oportunidades de acceso al deporte y a la recreaci\u00f3n.<\/p>\n<p>Por su parte, en la cancha sint\u00e9tica de f\u00fatbol 7 de la Unidad Deportiva Barrio Crist\u00f3bal, en el occidente de la ciudad, ya se ejecutaron las obras relacionadas con la estabilizaci\u00f3n del terreno, luego del deslizamiento e inestabilidad que afect\u00f3 el escenario. Como parte de la soluci\u00f3n t\u00e9cnica, dise\u00f1ada por profesionales especializados, se construy\u00f3 un muro de contenci\u00f3n en tierra armada para garantizar la seguridad de la zona intervenida.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-529896 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/la-comuna-doce-de-octubre-de-medellin-paso-del-miedo-y-el-desorden-a-la-reduccion-de-delitos-y-la-tranquilidad-en-sus-barrios\/imagen-panoramica-de-cancha-recuperada\/'><img width=\"1280\" height=\"720\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-recuperada.jpg\" class=\"attachment-full size-full\" alt=\"Imagen panor\u00e1mica de cancha recuperada\" loading=\"lazy\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-recuperada.jpg 1280w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-recuperada-300x169.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-recuperada-1024x576.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-recuperada-150x84.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-recuperada-768x432.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/la-comuna-doce-de-octubre-de-medellin-paso-del-miedo-y-el-desorden-a-la-reduccion-de-delitos-y-la-tranquilidad-en-sus-barrios\/imagen-panoramica-de-cancha-sintetica-recuperada\/'><img width=\"1280\" height=\"720\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-sintetica-recuperada.jpg\" class=\"attachment-full size-full\" alt=\"Imagen panor\u00e1mica de cancha sint\u00e9tica recuperada\" loading=\"lazy\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-sintetica-recuperada.jpg 1280w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-sintetica-recuperada-300x169.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-sintetica-recuperada-1024x576.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-sintetica-recuperada-150x84.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-panoramica-de-cancha-sintetica-recuperada-768x432.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Actualmente, las obras avanzan en m\u00e1s del 90 % con la construcci\u00f3n del muro de cerramiento y la instalaci\u00f3n de la malla perimetral sobre el sector afectado. Posteriormente, se realizar\u00e1 la nivelaci\u00f3n de la superficie de juego, la construcci\u00f3n del sistema filtrante y la instalaci\u00f3n del shockpad (capas de amortiguaci\u00f3n) y la nueva grama sint\u00e9tica bajo est\u00e1ndares FIFA Basic. Adem\u00e1s, el proyecto contempla la construcci\u00f3n de un and\u00e9n alrededor de la cancha para mejorar la movilidad y circulaci\u00f3n peatonal de los usuarios de la unidad deportiva.<\/p>\n<p>El director del <a href=\"https:\/\/www.inder.gov.co\/\" target=\"_blank\" rel=\"noopener\">Inder<\/a>, Eduardo Silva Meluk, dijo: \u201c<em>Seguimos entregando escenarios en Medell\u00edn. Escuchamos a la comunidad, sus necesidades y sabemos que todos est\u00e1n muy pendientes de las canchas de sus barrios. Vamos a entregarlas todas<\/em>\u201d.<\/p>\n<p><a href=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-de-cancha-sintetica-en-mal-estado.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"alignnone wp-image-529876 size-full\" title=\"cancha sint\u00e9tica en mal estado\" src=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-de-cancha-sintetica-en-mal-estado.jpg\" alt=\"Imagen de cancha sint\u00e9tica en mal estado\" width=\"1141\" height=\"760\" srcset=\"https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-de-cancha-sintetica-en-mal-estado.jpg 1141w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-de-cancha-sintetica-en-mal-estado-300x200.jpg 300w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-de-cancha-sintetica-en-mal-estado-1024x682.jpg 1024w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-de-cancha-sintetica-en-mal-estado-150x100.jpg 150w, https:\/\/www.medellin.gov.co\/es\/wp-content\/uploads\/2026\/05\/Imagen-de-cancha-sintetica-en-mal-estado-768x512.jpg 768w\" sizes=\"(max-width: 1141px) 100vw, 1141px\" \/><\/a><\/p>\n<p>Estas intervenciones hacen parte del plan de recuperaci\u00f3n y modernizaci\u00f3n de escenarios deportivos que adelanta la Administraci\u00f3n Distrital en toda la ciudad. A la fecha, la Alcald\u00eda de Medell\u00edn ha entregado 397 escenarios intervenidos, entre ellos 47 canchas sint\u00e9ticas, seis de ellas transformadas de arenilla a grama sint\u00e9tica, 90 polideportivas y 23 de tenis, adem\u00e1s de 11 pistas de skate, 78 gimnasios, zonas de barras y espacios de street workout (entrenamiento callejero), al igual que piscinas, ludotekas, parques infantiles y otros espacios recreativos y deportivos.<\/p>\n<p>Pr\u00f3ximamente, comenzar\u00e1n nuevas intervenciones en escenarios deportivos de comunas como Villa Hermosa y Buenos Aires, incluyendo canchas polideportivas, de baloncesto y microf\u00fatbol.<\/p>\n<p>Con estas acciones, la Administraci\u00f3n Distrital contin\u00faa consolidando una apuesta por el mejoramiento de espacios, como compromiso de ciudad, promoviendo que sean m\u00e1s seguros, modernos y adecuados para la recreaci\u00f3n, la actividad f\u00edsica y el deporte en los territorios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hasta la primera semana de mayo, la Administraci\u00f3n Distrital entreg\u00f3 397 escenarios deportivos recuperados y modernizados en diferentes comunas y corregimientos. Adem\u00e1s, nueve nuevos escenarios ya iniciaron obras y otros nueve comenzar\u00e1n intervenci\u00f3n pr\u00f3ximamente, como &#8230;<\/p>\n","protected":false},"author":21,"featured_media":529878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[747,26],"tags":[451,634,689,442],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/529896"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=529896"}],"version-history":[{"count":1,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/529896\/revisions"}],"predecessor-version":[{"id":529898,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/529896\/revisions\/529898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/529878"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=529896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=529896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=529896"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=529896"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=529896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}