{"id":63037,"date":"2022-02-18T00:00:00","date_gmt":"2022-02-18T05:00:00","guid":{"rendered":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/albergue-de-emergencias-de-medellin-ha-atendido-a-145-personas-en-situacion-de-vulnerabilidad-en-lo-corrido-del-ano\/"},"modified":"2022-02-18T00:00:00","modified_gmt":"2022-02-18T05:00:00","slug":"albergue-de-emergencias-de-medellin-ha-atendido-a-145-personas-en-situacion-de-vulnerabilidad-en-lo-corrido-del-ano","status":"publish","type":"post","link":"https:\/\/www.medellin.gov.co\/es\/sala-de-prensa\/noticias\/albergue-de-emergencias-de-medellin-ha-atendido-a-145-personas-en-situacion-de-vulnerabilidad-en-lo-corrido-del-ano\/","title":{"rendered":"Albergue de emergencias de Medell\u00edn ha atendido a 145 personas en situaci\u00f3n de vulnerabilidad en lo corrido del a\u00f1o"},"content":{"rendered":"<div class=\"wrap contenido\">\n<div class=\"noticia\">\n<div class=\"imagen\">\n<div class=\"divContImageNoticia input_plantilla input_background\" data-input=\"fotografia\" ruta=\"\/galerias\/Imagenes\/Galer\u00eda d\u00eda a d\u00eda 2022\/1000_450\/20220219-Adulto-Mayor-1.jpg\" fotografo=\"Foto Alcald\u00eda de Medell\u00edn\" descripcion=\"Albergue de emergencias de Medell\u00edn ha atendido a 145 personas en situaci\u00f3n de vulnerabilidad en lo corrido del a\u00f1o.\" style=\"background-image:url('\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer\u00eda d\u00eda a d\u00eda 2022\/1000_450\/20220219-Adulto-Mayor-1.jpg')\"><\/div>\n<p class=\"pMetaDesc\">Foto: Albergue de emergencias de Medell\u00edn ha atendido a 145 personas en situaci\u00f3n de vulnerabilidad en lo corrido del a\u00f1o.<\/p>\n<p class=\"pMetaFotografo\">Fot\u00f3grafo: Foto Alcald\u00eda de Medell\u00edn<\/p>\n<\/div>\n<p class=\"fecha\"><span class=\"input_plantilla input_text\" data-input=\"fecha\">2022-02-18<\/span><\/p>\n<h1 itemprop=\"name\" class=\"input_plantilla input_text\" data-input=\"titulo\">Albergue de emergencias de Medell\u00edn ha atendido a 145 personas en situaci\u00f3n de vulnerabilidad en lo corrido del a\u00f1o<\/h1>\n<h5 class=\"input_plantilla input_text\" data-input=\"autor\">Por Juli\u00e1n Piedrah\u00edta<\/h5>\n<div class=\"cuerpo input_plantilla input_area\" data-input=\"contenido\">\n<p>.: Las personas reciben alimentaci\u00f3n, acompa\u00f1amiento psicosocial y dormitorio, mientras se activan rutas de atenci\u00f3n de acuerdo con sus necesidades.<\/p>\n<p>.: Esta estrategia de la Administraci\u00f3n Municipal atiende, principalmente, a adultos mayores, migrantes y personas en riesgo de estar en situaci\u00f3n de calle.<\/p>\n<p>.: Las remisiones al albergue temporal se activan por llamadas a la L\u00ednea 123 Social y derivaciones de entidades del sector p\u00fablico, como el DAGRD, entre otras.<\/p>\n<p><a href=\"\/irj\/go\/km\/docs\/etc\/PortalMedellin\/archivos\/inclusion_social,_familia_y_ddhh\/20220219-Adulto-Mayor-01.mp3\" class=\"aContEnlace liMp3\" download=\"\" data-mce-href=\"\/irj\/go\/km\/docs\/etc\/PortalMedellin\/archivos\/inclusion_social,_familia_y_ddhh\/20220219-Adulto-Mayor-01.mp3\"><span>Palabras de Juan Pablo Ram\u00edrez \u00c1lvarez, secretario de Inclusi\u00f3n Social, Familia y Derechos Humanos.<\/span><span><\/span><span>1062 Kb<\/span><\/a><\/p>\n<p><a href=\"\/irj\/go\/km\/docs\/etc\/PortalMedellin\/archivos\/inclusion_social,_familia_y_ddhh\/20220219-Adulto-Mayor-02.mp3\" class=\"aContEnlace liMp3\" download=\"\" data-mce-href=\"\/irj\/go\/km\/docs\/etc\/PortalMedellin\/archivos\/inclusion_social,_familia_y_ddhh\/20220219-Adulto-Mayor-02.mp3\"><span>Palabras de Jaime Betancur S\u00e1nchez, beneficiario del albergue de emergencias.<\/span><span><\/span><span>627 Kb<\/span><\/a><\/p>\n<p>Como parte de la estrategia para brindar atenci\u00f3n a las personas en situaci\u00f3n de vulnerabilidad, este a\u00f1o la Alcald\u00eda de Medell\u00edn ha atendido a 145 personas en el albergue de emergencias, espacio disponible las 24 horas del d\u00eda y desde donde se direccionan las rutas de ayuda seg\u00fan el caso. En el a\u00f1o anterior, este espacio logr\u00f3 una cobertura de 895 personas atendidas, de las cuales el 30 % eran de otras nacionalidades.&nbsp;<\/p>\n<p>Las personas que pueden acceder a este albergue son aquellas que padecen emergencias sociales (como la violencia intrafamiliar), naturales (como los derrumbes) o antr\u00f3picas (como los incendios y otras causadas por el hombre). Los afectados pueden permanecer en \u00e9l algunas horas o varios meses seg\u00fan el proceso de activaci\u00f3n de rutas, sus necesidades y c\u00f3mo resolverlas.<\/p>\n<p>Sobre este albergue que funciona en el barrio Prado Centro, el secretario de Inclusi\u00f3n Social, Familia y Derechos Humanos, Juan Pablo Ram\u00edrez \u00c1lvarez, se\u00f1al\u00f3 que \u201c<em>en \u00e9l atendemos a quienes son m\u00e1s vulnerables y a quienes m\u00e1s lo necesitan. All\u00ed les damos atenci\u00f3n en enfermer\u00eda, dormitorio, alimentaci\u00f3n, atenci\u00f3n psicosocial y activamos rutas para que evitemos que las personas en medio de esta vulnerabilidad puedan pasar a estar en riesgo de situaci\u00f3n de calle<\/em>\u201d.<\/p>\n<p><a data-mce-href=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer%C3%ADa%20d%C3%ADa%20a%20d%C3%ADa%202022\/20220219-Adulto-Mayor-2.JPG\" href=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer%C3%ADa%20d%C3%ADa%20a%20d%C3%ADa%202022\/20220219-Adulto-Mayor-2.JPG\" title=\"Albergue de emergencias de Medell\u00edn ha atendido a 145 personas en situaci\u00f3n de vulnerabilidad en lo corrido del a\u00f1o\" target=\"_blank\" rel=\"noopener\"><img src=\"\/irj\/go\/km\/docs\/galerias\/Imagenes\/Galer%C3%ADa%20d%C3%ADa%20a%20d%C3%ADa%202022\/1000_450\/20220219-Adulto-Mayor-2.jpg\" alt=\"Albergue de emergencias de Medell\u00edn ha atendido a 145 personas en situaci\u00f3n de vulnerabilidad en lo corrido del a\u00f1o\" width=\"100%\"><\/a><br data-mce-bogus=\"1\"><\/p>\n<p>Dichas rutas pueden ser, por ejemplo, la remisi\u00f3n a un centro de protecci\u00f3n a personas mayores (u hogar gerontol\u00f3gico), el transporte humanitario hacia una zona de origen o punto de partida de un grupo de refugiados, o el otorgamiento de un auxilio habitacional en un hotel para una familia que perdi\u00f3 su vivienda en un desastre natural. Estas soluciones son servicios que, en su totalidad, presta la Administraci\u00f3n Municipal a problem\u00e1ticas sociales.&nbsp;<\/p>\n<p>Jaime Betancur S\u00e1nchez, beneficiario del albergue de emergencias, manifest\u00f3: \u201c<em>Llegu\u00e9 al albergue como habitante de calle hace cuatro meses y, desde ese momento, he recibido un trato respetuoso y profesional por parte de todo el personal. S\u00f3lo tengo agradecimiento. Me siento el hombre m\u00e1s feliz de la vida<\/em>\u201d.&nbsp;<\/p>\n<p>Los beneficiarios del albergue de emergencias pueden llegar tras comunicarse a la L\u00ednea 123 Social, al ser abordados por la comisi\u00f3n social de la Secretar\u00eda de Inclusi\u00f3n Social, Familia y Derechos Humanos o al ser remitidos desde dependencias de la Administraci\u00f3n Municipal como el DAGRD.<\/p>\n<\/div>\n<div class=\"compartir\">Compartir en:<a title=\"\" href=\"http:\/\/www.facebook.com\/share.php?u=\" class=\"btCompartirFacebook btCompartir\" target=\"_blank\" rel=\"noopener\"><\/a><a title=\"\" href=\"http:\/\/twitter.com\/home?status=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirTwitter btCompartir\"><\/a><a title=\"\" href=\"whatsapp:\/\/send?text=Haz%20clic%20para%20ver%20esta%20noticia%20en%20\" class=\"btCompartirWa btCompartir\"><\/a><\/div>\n<\/div>\n<p><script>try{comprobarImagen();fixBtnRedes();hitsMedellin();}catch(e){}<\/script><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Albergue de emergencias de Medell\u00edn ha atendido a 145 personas en situaci\u00f3n de vulnerabilidad en lo corrido del a\u00f1o. Fot\u00f3grafo: Foto Alcald\u00eda de Medell\u00edn 2022-02-18 Albergue de emergencias de Medell\u00edn ha atendido a 145 &#8230;<\/p>\n","protected":false},"author":1,"featured_media":63038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[451,435],"formato_nota":[],"programas_tax":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/63037"}],"collection":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/comments?post=63037"}],"version-history":[{"count":0,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/posts\/63037\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media\/63038"}],"wp:attachment":[{"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/media?parent=63037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/categories?post=63037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/tags?post=63037"},{"taxonomy":"formato_nota","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/formato_nota?post=63037"},{"taxonomy":"programas_tax","embeddable":true,"href":"https:\/\/www.medellin.gov.co\/es\/wp-json\/wp\/v2\/programas_tax?post=63037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}